{"id":142315,"date":"2021-07-19T08:14:01","date_gmt":"2021-07-19T06:14:01","guid":{"rendered":"https:\/\/tuzlainfo.ba\/?p=142315"},"modified":"2021-07-19T08:53:58","modified_gmt":"2021-07-19T06:53:58","slug":"bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom","status":"publish","type":"post","link":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/","title":{"rendered":"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom"},"content":{"rendered":"<p>Zbog kvara na cjevovodu, od ju\u010der je bez vode naselje Gornja Tuzla. Kako je saop\u0107eno iz JKP Vodovod i kanalizacija Tuzla,\u00a0 otklanjanje kvara o\u010dekuje se u toku dana. Vodosnabdijevanje ostalih podru\u010dja Grada Tuzla je uredno.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zbog kvara na cjevovodu, od ju\u010der je bez vode naselje Gornja Tuzla. Kako je saop\u0107eno iz JKP Vodovod i kanalizacija Tuzla,\u00a0 otklanjanje kvara o\u010dekuje se u toku dana. Vodosnabdijevanje ostalih podru\u010dja Grada Tuzla je uredno. &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":68032,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[304,12],"tags":[1442],"class_list":["post-142315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-istaknuto","category-novosti","tag-servisne-informacije"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/\" \/>\n<meta property=\"og:locale\" content=\"bs_BA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom\" \/>\n<meta property=\"og:description\" content=\"Zbog kvara na cjevovodu, od ju\u010der je bez vode naselje Gornja Tuzla. Kako je saop\u0107eno iz JKP Vodovod i kanalizacija Tuzla,\u00a0 otklanjanje kvara o\u010dekuje se u toku dana. Vodosnabdijevanje ostalih podru\u010dja Grada Tuzla je uredno. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/\" \/>\n<meta property=\"og:site_name\" content=\"TuzlaInfo.ba\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tuzlainfo.ba\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-19T06:14:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-19T06:53:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2019\/02\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tuzla Info\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tuzla Info\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/\"},\"author\":{\"name\":\"Tuzla Info\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#\\\/schema\\\/person\\\/46cad4c57790cbc50781edd14870825a\"},\"headline\":\"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom\",\"datePublished\":\"2021-07-19T06:14:01+00:00\",\"dateModified\":\"2021-07-19T06:53:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/\"},\"wordCount\":52,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tuzlainfo.ba\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg\",\"keywords\":[\"servisne informacije\"],\"articleSection\":[\"Istaknuto\",\"Novosti\"],\"inLanguage\":\"bs-BA\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/\",\"url\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/\",\"name\":\"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tuzlainfo.ba\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg\",\"datePublished\":\"2021-07-19T06:14:01+00:00\",\"dateModified\":\"2021-07-19T06:53:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#breadcrumb\"},\"inLanguage\":\"bs-BA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"bs-BA\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tuzlainfo.ba\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg\",\"contentUrl\":\"https:\\\/\\\/tuzlainfo.ba\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg\",\"width\":770,\"height\":578,\"caption\":\"2502 ViK Tuzla logo plava\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/index.php\\\/novosti\\\/item\\\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tuzlainfo.ba\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#website\",\"url\":\"https:\\\/\\\/tuzlainfo.ba\\\/\",\"name\":\"TuzlaInfo.ba\",\"description\":\"Tuzla info, gradski informator - Tuzla na dlanu\",\"publisher\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tuzlainfo.ba\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"bs-BA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#organization\",\"name\":\"TuzlaInfo.ba\",\"url\":\"https:\\\/\\\/tuzlainfo.ba\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bs-BA\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tuzlainfo.ba\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-ver-3-1.png\",\"contentUrl\":\"https:\\\/\\\/tuzlainfo.ba\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-ver-3-1.png\",\"width\":350,\"height\":95,\"caption\":\"TuzlaInfo.ba\"},\"image\":{\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tuzlainfo.ba\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tuzlainfo.ba\\\/#\\\/schema\\\/person\\\/46cad4c57790cbc50781edd14870825a\",\"name\":\"Tuzla Info\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bs-BA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e980921b00fa2e552723a2386544734ce6885d2b2304ccca3f45186f9ca4031d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e980921b00fa2e552723a2386544734ce6885d2b2304ccca3f45186f9ca4031d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e980921b00fa2e552723a2386544734ce6885d2b2304ccca3f45186f9ca4031d?s=96&d=mm&r=g\",\"caption\":\"Tuzla Info\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/","og_locale":"bs_BA","og_type":"article","og_title":"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom","og_description":"Zbog kvara na cjevovodu, od ju\u010der je bez vode naselje Gornja Tuzla. Kako je saop\u0107eno iz JKP Vodovod i kanalizacija Tuzla,\u00a0 otklanjanje kvara o\u010dekuje se u toku dana. Vodosnabdijevanje ostalih podru\u010dja Grada Tuzla je uredno. &nbsp;","og_url":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/","og_site_name":"TuzlaInfo.ba","article_publisher":"https:\/\/www.facebook.com\/tuzlainfo.ba\/","article_published_time":"2021-07-19T06:14:01+00:00","article_modified_time":"2021-07-19T06:53:58+00:00","og_image":[{"width":770,"height":578,"url":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2019\/02\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg","type":"image\/jpeg"}],"author":"Tuzla Info","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tuzla Info"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#article","isPartOf":{"@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/"},"author":{"name":"Tuzla Info","@id":"https:\/\/tuzlainfo.ba\/#\/schema\/person\/46cad4c57790cbc50781edd14870825a"},"headline":"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom","datePublished":"2021-07-19T06:14:01+00:00","dateModified":"2021-07-19T06:53:58+00:00","mainEntityOfPage":{"@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/"},"wordCount":52,"commentCount":0,"publisher":{"@id":"https:\/\/tuzlainfo.ba\/#organization"},"image":{"@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#primaryimage"},"thumbnailUrl":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2019\/02\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg","keywords":["servisne informacije"],"articleSection":["Istaknuto","Novosti"],"inLanguage":"bs-BA","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/tuzlainfo.ba\/#organization"}},{"@type":"WebPage","@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/","url":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/","name":"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom","isPartOf":{"@id":"https:\/\/tuzlainfo.ba\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#primaryimage"},"image":{"@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#primaryimage"},"thumbnailUrl":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2019\/02\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg","datePublished":"2021-07-19T06:14:01+00:00","dateModified":"2021-07-19T06:53:58+00:00","breadcrumb":{"@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#breadcrumb"},"inLanguage":"bs-BA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/"]}]},{"@type":"ImageObject","inLanguage":"bs-BA","@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#primaryimage","url":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2019\/02\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg","contentUrl":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2019\/02\/sadrzaj_2019_20190201_2502_ViK-Tuzla-logo-plava.jpg","width":770,"height":578,"caption":"2502 ViK Tuzla logo plava"},{"@type":"BreadcrumbList","@id":"https:\/\/tuzlainfo.ba\/index.php\/novosti\/item\/142315-bez-vode-jedno-naselje-u-tuzli-ostali-dijelovi-grada-uredno-snabdjeveni-vodom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tuzlainfo.ba\/"},{"@type":"ListItem","position":2,"name":"Bez vode jedno naselje u Tuzli, ostali dijelovi grada uredno snabdjeveni vodom"}]},{"@type":"WebSite","@id":"https:\/\/tuzlainfo.ba\/#website","url":"https:\/\/tuzlainfo.ba\/","name":"TuzlaInfo.ba","description":"Tuzla info, gradski informator - Tuzla na dlanu","publisher":{"@id":"https:\/\/tuzlainfo.ba\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tuzlainfo.ba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"bs-BA"},{"@type":"Organization","@id":"https:\/\/tuzlainfo.ba\/#organization","name":"TuzlaInfo.ba","url":"https:\/\/tuzlainfo.ba\/","logo":{"@type":"ImageObject","inLanguage":"bs-BA","@id":"https:\/\/tuzlainfo.ba\/#\/schema\/logo\/image\/","url":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2021\/03\/logo-ver-3-1.png","contentUrl":"https:\/\/tuzlainfo.ba\/wp-content\/uploads\/2021\/03\/logo-ver-3-1.png","width":350,"height":95,"caption":"TuzlaInfo.ba"},"image":{"@id":"https:\/\/tuzlainfo.ba\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tuzlainfo.ba\/"]},{"@type":"Person","@id":"https:\/\/tuzlainfo.ba\/#\/schema\/person\/46cad4c57790cbc50781edd14870825a","name":"Tuzla Info","image":{"@type":"ImageObject","inLanguage":"bs-BA","@id":"https:\/\/secure.gravatar.com\/avatar\/e980921b00fa2e552723a2386544734ce6885d2b2304ccca3f45186f9ca4031d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e980921b00fa2e552723a2386544734ce6885d2b2304ccca3f45186f9ca4031d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e980921b00fa2e552723a2386544734ce6885d2b2304ccca3f45186f9ca4031d?s=96&d=mm&r=g","caption":"Tuzla Info"}}]}},"_links":{"self":[{"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/posts\/142315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/comments?post=142315"}],"version-history":[{"count":0,"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/posts\/142315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/media\/68032"}],"wp:attachment":[{"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/media?parent=142315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/categories?post=142315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuzlainfo.ba\/index.php\/wp-json\/wp\/v2\/tags?post=142315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}